{"id":4350,"date":"2022-03-24T12:10:50","date_gmt":"2022-03-24T19:10:50","guid":{"rendered":"https:\/\/thewashroom.waterforpeople.org\/?p=4350"},"modified":"2022-03-24T12:10:51","modified_gmt":"2022-03-24T19:10:51","slug":"campana-de-movilizacion-para-mejorar-el-entorno-escolar","status":"publish","type":"post","link":"https:\/\/thewashroom.waterforpeople.org\/es\/campana-de-movilizacion-para-mejorar-el-entorno-escolar\/","title":{"rendered":"Soluciones para nuestros alumnos: Una campa\u00f1a de movilizaci\u00f3n para mejorar el entorno escolar\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Pritanu Mishra, Coordinador de Higiene y Saurya Sekhar Pal, Coordinador de Investigaci\u00f3n de Water For People India<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">English version <a href=\"https:\/\/thewashroom.waterforpeople.org\/?p=4349\">here<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\" \/>\n\n\n\n<p class=\"wp-block-paragraph\">El que da el primer paso podr\u00eda no alcanzar la meta; esto disuade a millones, pero motiva a miles a caminar. Esta historia refleja la uni\u00f3n de los departamentos gubernamentales, los profesores, padres, alumnos, y el personal de proyecto para ayudar a las escuelas a mejorar la operaci\u00f3n y el mantenimiento (OyM) de las instalaciones de Agua, Saneamiento e Higiene en escuelas (SWASH).\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Nuestros alumnos ahora tienen suficiente jab\u00f3n,\" afirma el director Sr. Upadhyay. \"\u00a1Una vez recibimos 505 jabones en una sola campa\u00f1a! Antes, los alumnos utilizaban un solo jab\u00f3n durante un mes.\" Los padres han estado donando jabones y materiales de limpieza en las colectas de jab\u00f3n organizadas regularmente por los profesores de <em>Sangha Mitra Higher Secondary Vidyalaya<\/em>, una escuela de 1.236 alumnos renovada por Water For People en India.\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Los alumnos proceden de familias pobres. Ni siquiera podemos pedir las cuotas de desarrollo escolar de \u20b9240\/- (US$3.28)<sup>1<\/sup>,\" comparti\u00f3 el director. \"Pagamos la contribuci\u00f3n de la escuela para renovar las instalaciones con nuestros propios salarios.\"\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco del programa SWASH, Water For People proporciona ba\u00f1os de colores separados para ni\u00f1os y ni\u00f1as con agua corriente, junto con estaciones dedicadas al lavado de manos y al agua potable. Water For People facilita que las autoridades escolares, los gobiernos locales y las comunidades tomen una decisi\u00f3n informada sobre la inversi\u00f3n en los costos de renovaci\u00f3n y de OyM (como los materiales de limpieza y los salarios de los limpiadores) para mejorar sus instalaciones ASH.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Ten\u00edamos que decidir si deb\u00edamos optar por optimizar los ba\u00f1os, ya que no tenemos fondos para hacer frente a los costos de mantenimiento. S\u00f3lo recibimos \u20b912.344\/- (US$170)<sup>2<\/sup> para el mantenimiento de la escuela,\" comparti\u00f3 el Sr. Gour Gopal Sinha, Director de la Escuela Primaria de <em>Jogarampur Bansberia<\/em>. \"Y no podemos pedir las cuotas escolares.\" Con la educaci\u00f3n gratuita hasta la clase VIII (ni\u00f1os de hasta 14 a\u00f1os), el pago de las cuotas escolares es una elecci\u00f3n que la mayor\u00eda de los padres se abstienen de contribuir \u2013 algunos por pobreza, otros por ignorancia.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la Ley del Derecho a la Educaci\u00f3n,<sup>3<\/sup> las escuelas dependen totalmente de los fondos del gobierno, que no cubren adecuadamente la OyM de las instalaciones ASH. Con pocos fondos, las instalaciones ASH se descuidan y se vuelven disfuncionales. Tanto en las zonas urbanas como en las rurales, la mayor\u00eda de los ba\u00f1os de las escuelas est\u00e1n sucios y con las puertas rotas. La mayor\u00eda de las escuelas rurales no tienen agua en los ba\u00f1os. Los alumnos evitan utilizar los ba\u00f1os salvo en caso de emergencia. Los ba\u00f1os de las escuelas est\u00e1n estigmatizados como sucios, apestosos y estropeados. \"Vamos al ba\u00f1o para hacer trampas durante los ex\u00e1menes, para fumar o en caso de emergencia,\" dijo un alumno de una escuela rural del Distrito de Howrah. \"Nadie mira en el ba\u00f1o para comprobar lo que estamos haciendo,\" se ri\u00f3 otro estudiante. Lo que antes era una parte fundamental de la gesti\u00f3n de residuos se convierte en un desperdicio.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El equipo de Water For People siempre est\u00e1 explorando nuevas estrategias para apoyar a las escuelas a la hora de afrontar estos gastos para garantizar la funcionalidad de los ba\u00f1os. \"Ten\u00eda la esperanza de que se produjera un cambio a trav\u00e9s de la promoci\u00f3n, porque en 2014 la Misi\u00f3n <em>Sarva Shiksha<\/em> de Calcuta reasign\u00f3 los gastos de las reuniones de la Asociaci\u00f3n de Madres y Maestros (AMM) para la compra de jabones para el lavado de manos,\" comparti\u00f3 Pritanu Mishra. El Sr. Mishra ha dirigido el programa de saneamiento escolar de Water For People en Bengala Occidental y ha abogado por la asignaci\u00f3n de fondos para los gastos de ASH en las escuelas. \"Antes, los profesores proporcionaban jabones para lavarse las manos a los alumnos.\"\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Teniendo en cuenta la dif\u00edcil situaci\u00f3n de las escuelas de todo el pa\u00eds, el Plan Integrado de Educaci\u00f3n Escolar (<em>Samagra Shikhsha<\/em>) del gobierno sancion\u00f3 un Grant Escolar Compuesto seg\u00fan el n\u00famero de alumnos matriculados en una escuela. Se sancionaron \u20b912.500\/- (US$170.88) para las escuelas con 15 o menos alumnos, \u20b925.000\/- (US$341.76) para las de 16 a 100 alumnos, \u20b950.000\/- (US$683) para las de 100 a 250, \u20b975.000\/- (US$1,025.29) para las de 250 a 1000, y \u20b91.00.000\/- (US$132) para las de m\u00e1s de 1.000 alumnos. El plan tambi\u00e9n obliga a las escuelas a gastar al menos el 10% del grant en el mantenimiento de los ba\u00f1os y en las actividades relacionadas con el Plan de Acci\u00f3n <em>Swachhata<\/em> (Limpieza), una iniciativa que marca un hito en la integraci\u00f3n de los elementos de limpieza en todos los sectores del gobierno de una manera elaborada, responsable y sostenida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Pero el 10% s\u00f3lo cubrir\u00eda los gastos de los barrenderos de \u20b9250\/- (US$3.41). Los gastos de material de limpieza y de jab\u00f3n siguen sin cubrirse, ya que la ayuda de fondos de \u20b9200\/- (US$2.73) para el jab\u00f3n se descontinu\u00f3,\" comparti\u00f3 el Sr. Mishra. \"Pensamos en involucrar a la AMM, los padres, los profesores y los Gabinetes de Ni\u00f1os<sup>4<\/sup> para decidir c\u00f3mo obtener fondos para cubrir los gastos.\"&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los intentos anteriores de preparar un presupuesto de mantenimiento de las instalaciones ASH con los profesores y los padres fueron in\u00fatiles porque no hab\u00eda fuentes de fondos. \"Al principio, el presupuesto de mantenimiento anual estaba siempre incompleto, ya que s\u00f3lo pod\u00edamos hacer la mitad [del trabajo]. Los profesores y tutores siempre dec\u00edan que la fuente de fondos era el gobierno local (<em>Gram Panchayat<\/em>),<em><sup>5<\/sup><\/em> y nunca se encontr\u00f3 la soluci\u00f3n,\" continu\u00f3 el Sr. Mishra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"As\u00ed que, cuando el Gabinete de Ni\u00f1os comparti\u00f3 que pedir\u00edan a otros alumnos que trajeran un jab\u00f3n, o cualquier material de limpieza, fue una soluci\u00f3n inimaginable. \u00a1Fue decidido por los alumnos, para los alumnos, de los alumnos!\" exclam\u00f3 el Sr. Mishra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los equipos organizan campa\u00f1as de recogida de jab\u00f3n en las escuelas, en las zonas rurales y urbanas de los Distritos de Howrah, Hooghly, Calcuta y Birbhum en Bengala Occidental. Los padres donaron jabones, cubos, desinfectantes y cepillos. Se anotaron en registros, guardados de forma segura bajo la supervisi\u00f3n del director.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos <em>panchayats<\/em> locales han empezado a incluir los gastos de <em>Nirmal Bandhu<\/em><sup>6<\/sup> en su Fondo de Desarrollo de los <em>Gram Panchayats<\/em>, lo que ha trasladado la carga de las escuelas al gobierno. \"El dinero as\u00ed ahorrado se utiliza mejor para las actividades de SWASH. Ahora limpiamos nuestras escuelas por lo menos tres veces a la semana, en lugar de una vez al mes,\" comparti\u00f3 un orgulloso y feliz profesor de la escuela<em> Boner Math Sabitribala<\/em> del Distrito de Hooghly.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\"Nuestro logro es que hemos cerrado la brecha entre la escuela, los tutores y el <em>panchayat<\/em>. Donde la escuela era [antes] percibida como propiedad del gobierno y los profesores como prestadores de servicios, ahora ambos son conscientes de los retos a los que se enfrenta cada uno, y ambos trabajan juntos. [El personal de Water For People] es un mero facilitador,\" sonr\u00ede Pritanu.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Este blog ha sido escrito con aportaciones directas del Sr. Pritanu Mishra, un sexagenario al que se le llama cari\u00f1osamente Pritanuda (\"da\" se a\u00f1ade como t\u00e9rmino de hermano mayor). Pritanuda ha pasado su carrera trabajando para los necesitados, movilizando al gobierno, a los medios de comunicaci\u00f3n y a los l\u00edderes pol\u00edticos. En su tiempo libre, trabaj\u00f3 para la Iglesia llegando a la comunidad. Su profundo conocimiento del saneamiento de las escuelas y del departamento de educaci\u00f3n le ha ayudado a alcanzar a los alumnos, a los profesores y a los tutores. Durante la pandemia del Covid-19, Pritanuda trabaj\u00f3 intensamente para impulsar el trabajo en las escuelas y la comunidad de Calcuta.\u00a0<\/em>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El Sr. Mishra fue diagnosticado con Covid-19 y falleci\u00f3 el 28 de abril de 2021.<\/em>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p><i> Por Pritanu Mishra y Saurya Sekhar Pal <\/i><br \/> Esta historia refleja la uni\u00f3n de los departamentos gubernamentales, los profesores, padres, alumnos, y el personal de proyecto para ayudar a las escuelas a mejorar la operaci\u00f3n y el mantenimiento (OyM) de las instalaciones de Agua, Saneamiento e Higiene en escuelas (SWASH ).\u00a0<\/p>","protected":false},"author":5,"featured_media":4351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[81,74,109,42,40,1683],"tags":[829],"class_list":["post-4350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bathroom","category-education","category-en-espanol","category-hygiene","category-sanitation","category-toilet-building","tag-espanol"],"_links":{"self":[{"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/posts\/4350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/comments?post=4350"}],"version-history":[{"count":3,"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/posts\/4350\/revisions"}],"predecessor-version":[{"id":4355,"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/posts\/4350\/revisions\/4355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/media\/4351"}],"wp:attachment":[{"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/media?parent=4350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/categories?post=4350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thewashroom.waterforpeople.org\/es\/wp-json\/wp\/v2\/tags?post=4350"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}